{"id":726,"count":2,"description":"","link":"https:\/\/www.franchisesolutions.com\/blog\/tag\/franchise-disclosure-document\/","name":"franchise disclosure document","slug":"franchise-disclosure-document","taxonomy":"post_tag","meta":[],"yoast_head":"\n<title>franchise disclosure document Archives - The Franchise Solutions Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"franchise disclosure document Archives - The Franchise Solutions Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.franchisesolutions.com\/blog\/tag\/franchise-disclosure-document\/\" \/>\n<meta property=\"og:site_name\" content=\"The Franchise Solutions Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n","yoast_head_json":{"title":"franchise disclosure document Archives - The Franchise Solutions Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"franchise disclosure document Archives - The Franchise Solutions Blog","og_url":"https:\/\/www.franchisesolutions.com\/blog\/tag\/franchise-disclosure-document\/","og_site_name":"The Franchise Solutions Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.franchisesolutions.com\/blog\/tag\/franchise-disclosure-document\/","url":"https:\/\/www.franchisesolutions.com\/blog\/tag\/franchise-disclosure-document\/","name":"franchise disclosure document Archives - The Franchise Solutions Blog","isPartOf":{"@id":"https:\/\/www.franchisesolutions.com\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.franchisesolutions.com\/blog\/#website","url":"https:\/\/www.franchisesolutions.com\/blog\/","name":"The Franchise Solutions Blog","description":"Connecting Franchisees &amp; Franchisors","publisher":{"@id":"https:\/\/www.franchisesolutions.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.franchisesolutions.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.franchisesolutions.com\/blog\/#organization","name":"The Franchise Solutions Blog","url":"https:\/\/www.franchisesolutions.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.franchisesolutions.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.franchisesolutions.com\/blog\/wp-content\/uploads\/2023\/02\/og-site-logo.png","contentUrl":"https:\/\/www.franchisesolutions.com\/blog\/wp-content\/uploads\/2023\/02\/og-site-logo.png","width":700,"height":427,"caption":"The Franchise Solutions Blog"},"image":{"@id":"https:\/\/www.franchisesolutions.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.franchisesolutions.com\/blog\/wp-json\/wp\/v2\/tags\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franchisesolutions.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.franchisesolutions.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.franchisesolutions.com\/blog\/wp-json\/wp\/v2\/posts?tags=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}